{"id":12667,"date":"2025-03-08T06:01:00","date_gmt":"2025-03-08T11:01:00","guid":{"rendered":"https:\/\/www.tce.gob.ec\/?p=12667"},"modified":"2025-03-11T11:45:15","modified_gmt":"2025-03-11T16:45:15","slug":"8-de-marzo-dia-internacional-de-la-mujer-2","status":"publish","type":"post","link":"https:\/\/www.tce.gob.ec\/index.php\/2025\/03\/08\/8-de-marzo-dia-internacional-de-la-mujer-2\/","title":{"rendered":"8 de marzo D\u00eda Internacional de la Mujer"},"content":{"rendered":"\n<p>En conmemoraci\u00f3n del 8 de marzo, D\u00eda Internacional de la Mujer, el Tribunal Contencioso Electoral (TCE) reafirma su compromiso por garantizar la igualdad y paridad en el ejercicio de los derechos pol\u00edticos y de participaci\u00f3n de los ciudadanos. Esta fecha, permite rememorar la lucha ejercida por la mujer para alcanzar una participaci\u00f3n en condiciones de igualdad con el hombre. Adem\u00e1s, brinda la oportunidad para reconocer su capacidad, resiliencia y unidad para conseguir logros fundamentales, como son: el derecho al voto; el acceso a la educaci\u00f3n y salud; y, la protecci\u00f3n laboral.<\/p>\n\n\n\n<p>Es preciso, tambi\u00e9n reconocer, a pesar de los avances alcanzados, persisten a\u00fan barreras de desigualdad, particularmente en el \u00e1mbito pol\u00edtico, donde las mujeres contin\u00faan enfrentando actitudes y pr\u00e1cticas que buscan limitar o anular su participaci\u00f3n activa. Por ello, el TCE en su misi\u00f3n de garantizar la igualdad en el ejercicio de los derechos pol\u00edticos, contin\u00faa trabajando en la identificaci\u00f3n y sanci\u00f3n de la Violencia Pol\u00edtica de G\u00e9nero. Adem\u00e1s, realiza esfuerzos constantes para socializar la normativa que refuerza el Estado Constitucional de Derechos y Justicia. Estas actividades, coadyuvan a eliminar las desigualdades persistentes y promueven la participaci\u00f3n efectiva de las mujeres en el \u00e1mbito pol\u00edtico.<\/p>\n\n\n\n<p>En este D\u00eda Internacional de la Mujer, como instituci\u00f3n hacemos un llamado a la reflexi\u00f3n sobre la importancia de continuar trabajando por la igualdad de g\u00e9nero. Esto permitir\u00e1, alcanzar el paradigma de una sociedad m\u00e1s justa y equitativa, en la que juntos y juntas construyamos una participaci\u00f3n y representaci\u00f3n pol\u00edtica fundamentada en la perspectiva de igualdad y paridad de g\u00e9nero.&nbsp;<\/p>\n<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-bottom-right\"><a href=\"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/12667?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><span class=\"pdfprnt-button-title pdfprnt-button-print-title\">Imprimir<\/span><\/a><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\nEn conmemoraci\u00f3n del 8 de marzo, D\u00eda Internacional de la Mujer, el Tribunal Contencioso Electoral (TCE) reafirma su&hellip;\n<\/div>\n<div class=\"link-more\"><a href=\"https:\/\/www.tce.gob.ec\/index.php\/2025\/03\/08\/8-de-marzo-dia-internacional-de-la-mujer-2\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &ldquo;8 de marzo D\u00eda Internacional de la Mujer&rdquo;<\/span>&hellip;<\/a><\/div>\n","protected":false},"author":11,"featured_media":12679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30],"tags":[],"table_tags":[],"class_list":["post-12667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","entry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/12667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/comments?post=12667"}],"version-history":[{"count":1,"href":"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/12667\/revisions"}],"predecessor-version":[{"id":12669,"href":"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/12667\/revisions\/12669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/media\/12679"}],"wp:attachment":[{"href":"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/media?parent=12667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/categories?post=12667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/tags?post=12667"},{"taxonomy":"table_tags","embeddable":true,"href":"https:\/\/www.tce.gob.ec\/index.php\/wp-json\/wp\/v2\/table_tags?post=12667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}